{"id":19846,"date":"2026-07-15T00:31:56","date_gmt":"2026-07-14T22:31:56","guid":{"rendered":"https:\/\/focolares.es\/?p=19846"},"modified":"2026-07-15T00:58:22","modified_gmt":"2026-07-14T22:58:22","slug":"contemplando-lo-esencial","status":"publish","type":"post","link":"https:\/\/focolares.es\/eu\/contemplando-lo-esencial\/","title":{"rendered":"Ezinbestekoa hausnartzen."},"content":{"rendered":"<h4 class=\"wp-block-heading\">La venida del Papa a Espa\u00f1a no ha sido \u00fanicamente un acontecimiento hist\u00f3rico o eclesial; ha sido una invitaci\u00f3n a levantar la vista, a redescubrir el horizonte de la esperanza y a volver el coraz\u00f3n hacia Dios.<\/h4>\n\n\n\n<div style=\"height:61px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Begira gora! <br>Me ha resonado como una llamada a salir de mis preocupaciones cotidianas para contemplar lo esencial: que Dios sigue caminando con su pueblo y contin\u00faa renovando la vida de quienes se abren a su presencia.<\/p>\n\n\n\n<p>En estos d\u00edas he podido experimentar una gracia especial, una experiencia sagrada que ha tocado el alma. He sentido que algo nuevo ha nacido en mi interior, como si el coraz\u00f3n hubiera sido restaurado y la fe reavivada. Es la certeza de que, cuando te encuentras con Cristo, el alma se regenera y recupera la alegr\u00eda, la paz y el sentido profundo de la vida.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"787\" src=\"https:\/\/focolares.es\/wp-content\/uploads\/2026\/07\/IMG_Experiencia_Tere_Papa_2026-1024x787.jpeg\" alt=\"\" class=\"wp-image-19870\" srcset=\"https:\/\/focolares.es\/wp-content\/uploads\/2026\/07\/IMG_Experiencia_Tere_Papa_2026-1024x787.jpeg 1024w, https:\/\/focolares.es\/wp-content\/uploads\/2026\/07\/IMG_Experiencia_Tere_Papa_2026-300x231.jpeg 300w, https:\/\/focolares.es\/wp-content\/uploads\/2026\/07\/IMG_Experiencia_Tere_Papa_2026-768x590.jpeg 768w, https:\/\/focolares.es\/wp-content\/uploads\/2026\/07\/IMG_Experiencia_Tere_Papa_2026-16x12.jpeg 16w, https:\/\/focolares.es\/wp-content\/uploads\/2026\/07\/IMG_Experiencia_Tere_Papa_2026.jpeg 1088w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Que esta visita no permanezca solo en el recuerdo, sino que se convierta en un impulso para seguir caminando con la mirada en alto, con esperanza renovada y con el compromiso de ser testigos del amor de Dios all\u00ed donde nos encontremos.<\/p>\n\n\n\n<p class=\"has-text-align-right\"><em>Tere<\/em><br><em>Madril<\/em><\/p>\n\n\n\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Esperanza renovada: un fruto de la visita de Le\u00f3n XIV.<\/p>","protected":false},"author":8,"featured_media":19869,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"footnotes":""},"categories":[1],"tags":[47,54],"class_list":["post-19846","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized","tag-iglesia","tag-testimonio"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Contemplando lo esencial - Movimiento de los Focolares<\/title>\n<meta name=\"description\" content=\"Esperanza renovada: un fruto de la visita de Le\u00f3n XIV. Testimonio.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/focolares.es\/eu\/contemplando-lo-esencial\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Contemplando lo esencial - Movimiento de los Focolares\" \/>\n<meta property=\"og:description\" content=\"Esperanza renovada: un fruto de la visita de Le\u00f3n XIV. Testimonio.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/focolares.es\/eu\/contemplando-lo-esencial\/\" \/>\n<meta property=\"og:site_name\" content=\"Movimiento de los Focolares\" \/>\n<meta property=\"article:published_time\" content=\"2026-07-14T22:31:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-14T22:58:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/focolares.es\/wp-content\/uploads\/2026\/07\/IMG_Experiencia_Tere_Papa_2026_3.2.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1088\" \/>\n\t<meta property=\"og:image:height\" content=\"725\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Sonia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sonia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutua\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/focolares.es\\\/contemplando-lo-esencial\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/focolares.es\\\/contemplando-lo-esencial\\\/\"},\"author\":{\"name\":\"Sonia\",\"@id\":\"https:\\\/\\\/focolares.es\\\/#\\\/schema\\\/person\\\/460a502493de84fa7b318667e9a5c289\"},\"headline\":\"Contemplando lo esencial\",\"datePublished\":\"2026-07-14T22:31:56+00:00\",\"dateModified\":\"2026-07-14T22:58:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/focolares.es\\\/contemplando-lo-esencial\\\/\"},\"wordCount\":195,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/focolares.es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/focolares.es\\\/contemplando-lo-esencial\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/focolares.es\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/IMG_Experiencia_Tere_Papa_2026_3.2.jpeg\",\"keywords\":[\"Iglesia\",\"Testimonio\"],\"articleSection\":[\"Uncategorized\"],\"inLanguage\":\"eu\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/focolares.es\\\/contemplando-lo-esencial\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/focolares.es\\\/contemplando-lo-esencial\\\/\",\"url\":\"https:\\\/\\\/focolares.es\\\/contemplando-lo-esencial\\\/\",\"name\":\"Contemplando lo esencial - Movimiento de los Focolares\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/focolares.es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/focolares.es\\\/contemplando-lo-esencial\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/focolares.es\\\/contemplando-lo-esencial\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/focolares.es\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/IMG_Experiencia_Tere_Papa_2026_3.2.jpeg\",\"datePublished\":\"2026-07-14T22:31:56+00:00\",\"dateModified\":\"2026-07-14T22:58:22+00:00\",\"description\":\"Esperanza renovada: un fruto de la visita de Le\u00f3n XIV. Testimonio.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/focolares.es\\\/contemplando-lo-esencial\\\/#breadcrumb\"},\"inLanguage\":\"eu\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/focolares.es\\\/contemplando-lo-esencial\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"eu\",\"@id\":\"https:\\\/\\\/focolares.es\\\/contemplando-lo-esencial\\\/#primaryimage\",\"url\":\"https:\\\/\\\/focolares.es\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/IMG_Experiencia_Tere_Papa_2026_3.2.jpeg\",\"contentUrl\":\"https:\\\/\\\/focolares.es\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/IMG_Experiencia_Tere_Papa_2026_3.2.jpeg\",\"width\":1088,\"height\":725},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/focolares.es\\\/contemplando-lo-esencial\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/focolares.es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Contemplando lo esencial\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/focolares.es\\\/#website\",\"url\":\"https:\\\/\\\/focolares.es\\\/\",\"name\":\"Movimiento de los Focolares\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/focolares.es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/focolares.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"eu\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/focolares.es\\\/#organization\",\"name\":\"Movimiento de los Focolares\",\"url\":\"https:\\\/\\\/focolares.es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"eu\",\"@id\":\"https:\\\/\\\/focolares.es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/focolares.es\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Logo_focolares-1024x944-1.jpg\",\"contentUrl\":\"https:\\\/\\\/focolares.es\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Logo_focolares-1024x944-1.jpg\",\"width\":1024,\"height\":944,\"caption\":\"Movimiento de los Focolares\"},\"image\":{\"@id\":\"https:\\\/\\\/focolares.es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/focolares.es\\\/#\\\/schema\\\/person\\\/460a502493de84fa7b318667e9a5c289\",\"name\":\"Sonia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"eu\",\"@id\":\"https:\\\/\\\/focolares.es\\\/wp-content\\\/litespeed\\\/avatar\\\/cdad09e33a37c7312cdc76ceae4bbc88.jpg?ver=1784032935\",\"url\":\"https:\\\/\\\/focolares.es\\\/wp-content\\\/litespeed\\\/avatar\\\/cdad09e33a37c7312cdc76ceae4bbc88.jpg?ver=1784032935\",\"contentUrl\":\"https:\\\/\\\/focolares.es\\\/wp-content\\\/litespeed\\\/avatar\\\/cdad09e33a37c7312cdc76ceae4bbc88.jpg?ver=1784032935\",\"caption\":\"Sonia\"},\"url\":\"https:\\\/\\\/focolares.es\\\/eu\\\/author\\\/sonia\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Contemplando lo esencial - Movimiento de los Focolares","description":"Esperanza renovada: un fruto de la visita de Le\u00f3n XIV. Testimonio.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/focolares.es\/eu\/contemplando-lo-esencial\/","og_locale":"en_US","og_type":"article","og_title":"Contemplando lo esencial - Movimiento de los Focolares","og_description":"Esperanza renovada: un fruto de la visita de Le\u00f3n XIV. Testimonio.","og_url":"https:\/\/focolares.es\/eu\/contemplando-lo-esencial\/","og_site_name":"Movimiento de los Focolares","article_published_time":"2026-07-14T22:31:56+00:00","article_modified_time":"2026-07-14T22:58:22+00:00","og_image":[{"width":1088,"height":725,"url":"https:\/\/focolares.es\/wp-content\/uploads\/2026\/07\/IMG_Experiencia_Tere_Papa_2026_3.2.jpeg","type":"image\/jpeg"}],"author":"Sonia","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Sonia","Est. reading time":"2 minutua"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/focolares.es\/contemplando-lo-esencial\/#article","isPartOf":{"@id":"https:\/\/focolares.es\/contemplando-lo-esencial\/"},"author":{"name":"Sonia","@id":"https:\/\/focolares.es\/#\/schema\/person\/460a502493de84fa7b318667e9a5c289"},"headline":"Contemplando lo esencial","datePublished":"2026-07-14T22:31:56+00:00","dateModified":"2026-07-14T22:58:22+00:00","mainEntityOfPage":{"@id":"https:\/\/focolares.es\/contemplando-lo-esencial\/"},"wordCount":195,"commentCount":0,"publisher":{"@id":"https:\/\/focolares.es\/#organization"},"image":{"@id":"https:\/\/focolares.es\/contemplando-lo-esencial\/#primaryimage"},"thumbnailUrl":"https:\/\/focolares.es\/wp-content\/uploads\/2026\/07\/IMG_Experiencia_Tere_Papa_2026_3.2.jpeg","keywords":["Iglesia","Testimonio"],"articleSection":["Uncategorized"],"inLanguage":"eu","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/focolares.es\/contemplando-lo-esencial\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/focolares.es\/contemplando-lo-esencial\/","url":"https:\/\/focolares.es\/contemplando-lo-esencial\/","name":"Contemplando lo esencial - Movimiento de los Focolares","isPartOf":{"@id":"https:\/\/focolares.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/focolares.es\/contemplando-lo-esencial\/#primaryimage"},"image":{"@id":"https:\/\/focolares.es\/contemplando-lo-esencial\/#primaryimage"},"thumbnailUrl":"https:\/\/focolares.es\/wp-content\/uploads\/2026\/07\/IMG_Experiencia_Tere_Papa_2026_3.2.jpeg","datePublished":"2026-07-14T22:31:56+00:00","dateModified":"2026-07-14T22:58:22+00:00","description":"Esperanza renovada: un fruto de la visita de Le\u00f3n XIV. Testimonio.","breadcrumb":{"@id":"https:\/\/focolares.es\/contemplando-lo-esencial\/#breadcrumb"},"inLanguage":"eu","potentialAction":[{"@type":"ReadAction","target":["https:\/\/focolares.es\/contemplando-lo-esencial\/"]}]},{"@type":"ImageObject","inLanguage":"eu","@id":"https:\/\/focolares.es\/contemplando-lo-esencial\/#primaryimage","url":"https:\/\/focolares.es\/wp-content\/uploads\/2026\/07\/IMG_Experiencia_Tere_Papa_2026_3.2.jpeg","contentUrl":"https:\/\/focolares.es\/wp-content\/uploads\/2026\/07\/IMG_Experiencia_Tere_Papa_2026_3.2.jpeg","width":1088,"height":725},{"@type":"BreadcrumbList","@id":"https:\/\/focolares.es\/contemplando-lo-esencial\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/focolares.es\/"},{"@type":"ListItem","position":2,"name":"Contemplando lo esencial"}]},{"@type":"WebSite","@id":"https:\/\/focolares.es\/#website","url":"https:\/\/focolares.es\/","name":"Fokolareen Mugimenduaren","description":"","publisher":{"@id":"https:\/\/focolares.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/focolares.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"eu"},{"@type":"Organization","@id":"https:\/\/focolares.es\/#organization","name":"Fokolareen Mugimenduaren","url":"https:\/\/focolares.es\/","logo":{"@type":"ImageObject","inLanguage":"eu","@id":"https:\/\/focolares.es\/#\/schema\/logo\/image\/","url":"https:\/\/focolares.es\/wp-content\/uploads\/2024\/03\/Logo_focolares-1024x944-1.jpg","contentUrl":"https:\/\/focolares.es\/wp-content\/uploads\/2024\/03\/Logo_focolares-1024x944-1.jpg","width":1024,"height":944,"caption":"Movimiento de los Focolares"},"image":{"@id":"https:\/\/focolares.es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/focolares.es\/#\/schema\/person\/460a502493de84fa7b318667e9a5c289","name":"Sonia","image":{"@type":"ImageObject","inLanguage":"eu","@id":"https:\/\/focolares.es\/wp-content\/litespeed\/avatar\/cdad09e33a37c7312cdc76ceae4bbc88.jpg?ver=1784032935","url":"https:\/\/focolares.es\/wp-content\/litespeed\/avatar\/cdad09e33a37c7312cdc76ceae4bbc88.jpg?ver=1784032935","contentUrl":"https:\/\/focolares.es\/wp-content\/litespeed\/avatar\/cdad09e33a37c7312cdc76ceae4bbc88.jpg?ver=1784032935","caption":"Sonia"},"url":"https:\/\/focolares.es\/eu\/author\/sonia\/"}]}},"views":0,"_links":{"self":[{"href":"https:\/\/focolares.es\/eu\/wp-json\/wp\/v2\/posts\/19846","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/focolares.es\/eu\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/focolares.es\/eu\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/focolares.es\/eu\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/focolares.es\/eu\/wp-json\/wp\/v2\/comments?post=19846"}],"version-history":[{"count":8,"href":"https:\/\/focolares.es\/eu\/wp-json\/wp\/v2\/posts\/19846\/revisions"}],"predecessor-version":[{"id":19875,"href":"https:\/\/focolares.es\/eu\/wp-json\/wp\/v2\/posts\/19846\/revisions\/19875"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/focolares.es\/eu\/wp-json\/wp\/v2\/media\/19869"}],"wp:attachment":[{"href":"https:\/\/focolares.es\/eu\/wp-json\/wp\/v2\/media?parent=19846"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/focolares.es\/eu\/wp-json\/wp\/v2\/categories?post=19846"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/focolares.es\/eu\/wp-json\/wp\/v2\/tags?post=19846"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}