{"id":15312,"date":"2025-02-24T18:07:00","date_gmt":"2025-02-24T17:07:00","guid":{"rendered":"https:\/\/focolares.es\/?p=15312"},"modified":"2025-03-27T21:24:19","modified_gmt":"2025-03-27T20:24:19","slug":"proximidade-e-liberdade","status":"publish","type":"post","link":"https:\/\/focolares.es\/gl\/proximidad-y-libertad\/","title":{"rendered":"Proximidade e liberdade"},"content":{"rendered":"<h4 class=\"wp-block-heading\"><em>Publicamos a entrevista a Margaret Karram, presidenta do Movemento dos Focolares, realizada por Peter Forst para a revista Neue Stadt sobre o tema que o Movemento dos Focolares explora e vive este ano: a proximidade. Non se trata s\u00f3 dunha actitude relixiosa ou espiritual, sen\u00f3n tam\u00e9n civil e social, a prol da paz e da axuda aos pobres, mellorando a calidade das relaci\u00f3ns entre as persoas, respectando a liberdade e a conciencia dos demais.<\/em><\/h4>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><strong><em>Margaret, por que escolleches a proximidade como tema do ano do Movemento dos Focolares?<\/em><\/strong><\/p>\n\n\n\n<p>Pregunt\u00e1bame en que mundo vivimos, e par\u00e9ceme que a estas alturas da historia hai moita soidade e indiferenza. Tam\u00e9n hai unha escalada de violencia, de guerras que causan tanta dor en todo o mundo. Tam\u00e9n pensei na tecnolox\u00eda que nos conectou de xeitos nunca antes co\u00f1ecidos, pero que ao mesmo tempo nos fai cada vez m\u00e1is individualistas. Nun mundo coma este creo que a proximidade pode ser un ant\u00eddoto; unha axuda para superar estes obst\u00e1culos e curar estes \u201cmales\u201d que nos afastan uns dos outros.<\/p>\n\n\n\n<p><strong><em>Por onde podemos comezar?<\/em><\/strong><\/p>\n\n\n\n<p>Levo meses fac\u00e9ndome esta pregunta. Par\u00e9ceme que hai que reaprender a achegarse \u00e1 xente, reaprender a ver e tratar a todos coma irm\u00e1ns. Sent\u00edn que antes de nada ti\u00f1a que facer unha indagaci\u00f3n sobre a mi\u00f1a actitude. As persoas que co\u00f1ezo todos os d\u00edas son irm\u00e1ns para min? Ou son indiferente cara a eles ou mesmo os considero inimigos? F\u00edxenme moitas preguntas. Descubr\u00edn que \u00e1s veces quero evitar a unha persoa porque pode molestarme, facerme sentir inc\u00f3modo ou querer falar comigo de situaci\u00f3ns dif\u00edciles. Por todos estes motivos, titulei a mi\u00f1a reflexi\u00f3n sobre a proximidade \u2014que presentei a mediados de novembro aos responsables do Movemento dos Focolares\u2014 \u201cQuen es ti para min?\u201d.<\/p>\n\n\n\n<p><strong><em>Poder\u00edas contarnos algunhas das principais ideas que desenvolveches baixo este t\u00edtulo?<\/em><\/strong><\/p>\n\n\n\n<p>Con pracer. Vou mencionar catro reflexi\u00f3ns. A primeira proximidade que experimenta a nosa alma \u00e9 a do contacto con Deus. \u00c9 El mesmo quen se transmite aos nosos veci\u00f1os a trav\u00e9s de n\u00f3s. O desexo de amar ao outro \u00e9 un movemento que desde Deus en min quere ir cara a Deus no outro.<\/p>\n\n\n\n<p>Unha segunda reflexi\u00f3n: a proximidade \u00e9 din\u00e1mica. Esixe apertura total, \u00e9 dicir, acoller \u00e1 xente sen reservas; entrar na s\u00faa forma de ver as cousas. Non somos producidos en masa! Cada un de n\u00f3s \u00e9 \u00fanico, cun car\u00e1cter, mentalidade, cultura, vida e historia diferentes. Reco\u00f1ecer e respectar isto esixe que saiamos dos nosos marcos mentais e persoais.<\/p>\n\n\n\n<p><strong><em>Falabas dun terceiro aspecto...<\/em><\/strong><\/p>\n\n\n\n<p>Si. O terceiro aspecto que quero subli\u00f1ar \u00e9 que a proximidade non coincide necesariamente coa proximidade, con semellanza, coa pertenza a un mesmo horizonte cultural. A par\u00e1bola do bo samaritano (Lc 10,25-37) expr\u00e9sao moi ben. Chamoume a atenci\u00f3n a actitude do samaritano: o home que caera entre os bandidos era un desco\u00f1ecido para el, mesmo doutro pobo. Era unha persoa distante tanto por cultura como por tradici\u00f3n. Pero o samaritano f\u00edxose o seu veci\u00f1o. Este \u00e9 o punto clave para min. Cada un ten a s\u00faa propia dignidade, independentemente da s\u00faa orixe, cultura ou car\u00e1cter. O samaritano non se limitou a achegarse para ver se esta persoa estaba ferida e despois marchou ou, en todo caso, pediu axuda. F\u00edxose veci\u00f1o e coidaba da persoa. O cuarto aspecto...<\/p>\n\n\n\n<p><strong><em>\u2026 eu ser\u00eda\u2026<\/em><\/strong><\/p>\n\n\n\n<p>Isto significa: deixarnos cuestionar, expo\u00f1ernos a preguntas para as que non temos resposta; estar dispostos a mostrarnos vulnerables; quizais present\u00e1ndonos como d\u00e9biles e incapaces. O efecto de tal actitude pode ser sorprendente. Imaxinade, un neno de nove anos escribiume que para el a proximidade significa &quot;levantar o coraz\u00f3n do outro&quot;. Non \u00e9 este un efecto marabilloso de proximidade? Levanta o coraz\u00f3n dos demais... deixarnos ferir. Para que a proximidade dea os seus froitos, p\u00eddenos a cada un de n\u00f3s que non te\u00f1amos medo e que nos deixemos ferir polo outro.<\/p>\n\n\n\n<p><strong><em>Que cambiar\u00eda no Movemento dos Focolares se vivisemos ben a proximidade?<\/em><\/strong><\/p>\n\n\n\n<p>Se realmente o vivimos ben, moitas cousas cambiar\u00e1n. Desexo, espero e rezo para que as\u00ed sexa. Pero tam\u00e9n quero subli\u00f1ar que moitos do Movemento dos Focolares xa experimentan proximidade. Son innumerables as iniciativas, moitos proxectos que promoven a paz e axudan aos m\u00e1is necesitados. Incluso abrimos focolares para prestar asistencia e acollida aos inmigrantes ou para coidar a natureza.<\/p>\n\n\n\n<p><strong><em>E que deber\u00eda cambiar?<\/em><\/strong><\/p>\n\n\n\n<p>A calidade das relaci\u00f3ns entre as persoas. \u00c1s veces \u00e9 m\u00e1is f\u00e1cil tratar ben \u00e1s persoas alleas ao Movemento, pero \u00e9 m\u00e1is dif\u00edcil tratar aos que formamos parte da mesma familia. Corremos o risco de vivir entre n\u00f3s en relaci\u00f3ns &quot;ben educadas&quot;: non nos lastimamos, pero preg\u00fantome, \u00e9 unha relaci\u00f3n aut\u00e9ntica?<\/p>\n\n\n\n<p>Por iso espero que, m\u00e1is al\u00e1 dos proxectos, a proximidade se converta nun estilo de vida coti\u00e1; que nos preguntamos varias veces ao d\u00eda: Estou experimentando esta proximidade? Como o vivo? Unha expresi\u00f3n importante de proximidade \u00e9 o perd\u00f3n. Sexa misericordioso cos demais e con n\u00f3s mesmos.<\/p>\n\n\n\n<p><strong><em>Que mensaxe cont\u00e9n para a sociedade?<\/em><\/strong><\/p>\n\n\n\n<p>A proximidade non \u00e9 s\u00f3 unha actitude relixiosa ou espiritual, sen\u00f3n tam\u00e9n civil e social. \u00c9 posible experimentalo en calquera ambiente. No \u00e1mbito da educaci\u00f3n, por exemplo, ou da medicina, ou mesmo da pol\u00edtica, onde quizais sexa m\u00e1is dif\u00edcil. Se o vivimos ben, podemos influ\u00edr positivamente nas relaci\u00f3ns esteamos onde esteamos.<\/p>\n\n\n\n<p><strong><em>E para a Igrexa?<\/em><\/strong><\/p>\n\n\n\n<p>A Igrexa existe porque coa chegada de Xes\u00fas, Deus f\u00edxose o noso pr\u00f3ximo. A Igrexa, as Igrexas, est\u00e1n, pois, chamadas a dar testemu\u00f1o dunha proximidade vivida. A Igrexa Cat\u00f3lica celebrou recentemente un S\u00ednodo. Puiden participar nas d\u00faas sesi\u00f3ns no Vaticano. Eramos m\u00e1is de 300 persoas, cada unha dunha cultura diferente. Que fixemos? Un exercicio de sinodalidade, un exercicio de escoita, de comprensi\u00f3n profunda, de acoller os pensamentos dos demais, os seus retos e a s\u00faa dor. Todas elas son caracter\u00edsticas de proximidade.<\/p>\n\n\n\n<p>O t\u00edtulo do S\u00ednodo foi &quot;Cami\u00f1ando xuntos&quot;. Este cami\u00f1o implicou moitas persoas en todo o mundo. O logotipo do S\u00ednodo expresaba o desexo de ampliar a carpa da Igrexa para que ningu\u00e9n se sinta exclu\u00eddo. Par\u00e9ceme que este \u00e9 o verdadeiro significado da proximidade: que ningu\u00e9n est\u00e1 exclu\u00eddo; que todos se sintan acollidos, tanto os que asisten \u00e1 Igrexa como os que al\u00ed non se reco\u00f1ecen ou os que mesmo se distanciaron por diversas raz\u00f3ns.<\/p>\n\n\n\n<p><strong><em>Gustar\u00edame mencionar por un momento os l\u00edmites da proximidade. Como vivilo ben?<\/em><\/strong><\/p>\n\n\n\n<p>\u00c9 unha pregunta importante. Hai l\u00edmites \u00e1 proximidade? Como primeira resposta dir\u00eda que non deber\u00eda haber l\u00edmites.<\/p>\n\n\n\n<p><strong><em>Pero?<\/em><\/strong><\/p>\n\n\n\n<p>Non podemos estar seguros de que o que \u00e9 proximidade e solidariedade para n\u00f3s, ou para min, \u00e9 o que \u00e9 proximidade e solidariedade para o outro. Nunha relaci\u00f3n nunca pode faltar o respecto \u00e1 liberdade e \u00e1 conciencia do outro. Estas d\u00faas cousas son esenciais en toda relaci\u00f3n. Por iso \u00e9 importante que cando nos achegamos a algu\u00e9n, o fagamos sempre con suavidade e non como algo que lle impo\u00f1amos. \u00c9 a outra persoa quen decide canto e que tipo de proximidade quere.<\/p>\n\n\n\n<p><strong><em>Hai moito que aprender, non?<\/em><\/strong><\/p>\n\n\n\n<p>Absolutamente si. Cometemos varios erros. Pensando que amamos ao outro, fix\u00e9moslle dano. A trav\u00e9s do noso desexo de comunicar a nosa espiritualidade, constru\u00edmos relaci\u00f3ns nas que o outro non sempre se sentiu libre. \u00c1s veces par\u00e9ceme que, coa boa intenci\u00f3n de querer a unha persoa, a esmagamos. Non mostramos a suficiente sensibilidade e respecto pola conciencia dos demais, pola liberdade dos demais, polo tempo dos demais. E isto levou a certas formas de paternalismo e mesmo de abuso.<\/p>\n\n\n\n<p>Sen d\u00fabida, esta \u00e9 unha situaci\u00f3n moi dolorosa \u00e1 que nos enfrontamos, e na que as v\u00edtimas te\u00f1en unha importancia \u00fanica, verdadeiramente \u00fanica. Porque s\u00f3s non podemos entender ben o que pasou. Son as v\u00edtimas as que nos axudan a comprender os erros que cometemos e a tomar as medidas necesarias para que estas cousas non volvan ocorrer.<\/p>\n\n\n\n<p><strong><em>Un \u00faltimo desexo?<\/em><\/strong><\/p>\n\n\n\n<p>Espero que este tema poida devolvernos \u00e1 esencia do que o propio Xes\u00fas nos deu no Evanxeo. P\u00faxonos moitos exemplos do que significa vivir de proximidade.<\/p>\n\n\n\n<p>Hai un pensamento de Chiara Lubich que me resoou moi forte ao pensar neste tema. Di:&nbsp;<em>&quot;Hai quen fai cousas &#039;por amor&#039; e hai quen fai cousas intentando &#039;ser amor&#039;. O amor habita en Deus, e Deus \u00e9 Amor, pero o Amor que \u00e9 Deus \u00e9 luz, e coa luz vemos se a nosa forma de achegarnos e de servir ao irm\u00e1n \u00e9 conforme ao Coraz\u00f3n de Deus, como desexar\u00eda o noso irm\u00e1n, como so\u00f1ar\u00eda se n\u00f3s non estiv\u00e9semos ao seu car\u00f3n, sen\u00f3n a Xes\u00fas.<\/em><\/p>\n\n\n\n<p><strong><em>Grazas dende o fondo do meu coraz\u00f3n, Margaret, pola t\u00faa paix\u00f3n pola proximidade vivida con determinaci\u00f3n e respecto.<\/em><\/strong><\/p>\n\n\n\n<p class=\"has-text-align-right\"><em>Peter Forst<\/em><br><em>(Publicado na revista&nbsp;<a href=\"https:\/\/www.neuestadt.com\/de\/zeitschriften\/monatsmagazin-neue-stadt\/zeitschrift-neue-stadt.html\" target=\"_blank\" rel=\"noreferrer noopener\">Cidade Nova<\/a>)<\/em><br><em>Foto: \u00a9 Austin Im-CSC Audiovisivi<\/em><\/p>","protected":false},"excerpt":{"rendered":"<p>Entrevista a Margaret Karram, presidenta do Movemento dos Focolares, realizada por Peter Forst para a revista Neue Stadt sobre o tema do ano: a proximidade. <\/p>","protected":false},"author":1,"featured_media":15402,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"footnotes":""},"categories":[1],"tags":[49],"class_list":["post-15312","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized","tag-entrevista"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Proximidad y libertad - Movimiento de los Focolares<\/title>\n<meta name=\"description\" content=\"Entrevista a la presidenta de los Focolares, realizada por Peter Forst para la revista Neue Stadt sobre el tema del a\u00f1o: la proximidad.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/focolares.es\/gl\/proximidade-e-liberdade\/\" \/>\n<meta property=\"og:locale\" content=\"gl_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Proximidad y libertad - Movimiento de los Focolares\" \/>\n<meta property=\"og:description\" content=\"Entrevista a la presidenta de los Focolares, realizada por Peter Forst para la revista Neue Stadt sobre el tema del a\u00f1o: la proximidad.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/focolares.es\/gl\/proximidade-e-liberdade\/\" \/>\n<meta property=\"og:site_name\" content=\"Movimiento de los Focolares\" \/>\n<meta property=\"article:published_time\" content=\"2025-02-24T17:07:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-27T20:24:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/focolares.es\/wp-content\/uploads\/2025\/02\/Margaret-DSC00871-400x250-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/focolares.es\\\/proximidad-y-libertad\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/focolares.es\\\/proximidad-y-libertad\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/focolares.es\\\/#\\\/schema\\\/person\\\/fdbf1cac3e3957f836bf607a31e7616d\"},\"headline\":\"Proximidad y libertad\",\"datePublished\":\"2025-02-24T17:07:00+00:00\",\"dateModified\":\"2025-03-27T20:24:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/focolares.es\\\/proximidad-y-libertad\\\/\"},\"wordCount\":1643,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/focolares.es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/focolares.es\\\/proximidad-y-libertad\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/focolares.es\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Margaret-DSC00871-400x250-1.jpg\",\"keywords\":[\"Entrevista\"],\"articleSection\":[\"Uncategorized\"],\"inLanguage\":\"gl-ES\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/focolares.es\\\/proximidad-y-libertad\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/focolares.es\\\/proximidad-y-libertad\\\/\",\"url\":\"https:\\\/\\\/focolares.es\\\/proximidad-y-libertad\\\/\",\"name\":\"Proximidad y libertad - Movimiento de los Focolares\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/focolares.es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/focolares.es\\\/proximidad-y-libertad\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/focolares.es\\\/proximidad-y-libertad\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/focolares.es\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Margaret-DSC00871-400x250-1.jpg\",\"datePublished\":\"2025-02-24T17:07:00+00:00\",\"dateModified\":\"2025-03-27T20:24:19+00:00\",\"description\":\"Entrevista a la presidenta de los Focolares, realizada por Peter Forst para la revista Neue Stadt sobre el tema del a\u00f1o: la proximidad.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/focolares.es\\\/proximidad-y-libertad\\\/#breadcrumb\"},\"inLanguage\":\"gl-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/focolares.es\\\/proximidad-y-libertad\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"gl-ES\",\"@id\":\"https:\\\/\\\/focolares.es\\\/proximidad-y-libertad\\\/#primaryimage\",\"url\":\"https:\\\/\\\/focolares.es\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Margaret-DSC00871-400x250-1.jpg\",\"contentUrl\":\"https:\\\/\\\/focolares.es\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Margaret-DSC00871-400x250-1.jpg\",\"width\":800,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/focolares.es\\\/proximidad-y-libertad\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/focolares.es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Proximidad y libertad\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/focolares.es\\\/#website\",\"url\":\"https:\\\/\\\/focolares.es\\\/\",\"name\":\"Movimiento de los Focolares\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/focolares.es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/focolares.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"gl-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/focolares.es\\\/#organization\",\"name\":\"Movimiento de los Focolares\",\"url\":\"https:\\\/\\\/focolares.es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"gl-ES\",\"@id\":\"https:\\\/\\\/focolares.es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/focolares.es\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Logo_focolares-1024x944-1.jpg\",\"contentUrl\":\"https:\\\/\\\/focolares.es\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Logo_focolares-1024x944-1.jpg\",\"width\":1024,\"height\":944,\"caption\":\"Movimiento de los Focolares\"},\"image\":{\"@id\":\"https:\\\/\\\/focolares.es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/focolares.es\\\/#\\\/schema\\\/person\\\/fdbf1cac3e3957f836bf607a31e7616d\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"gl-ES\",\"@id\":\"https:\\\/\\\/focolares.es\\\/wp-content\\\/litespeed\\\/avatar\\\/ba00c276ce0fa7863cda4038d70907a8.jpg?ver=1784037436\",\"url\":\"https:\\\/\\\/focolares.es\\\/wp-content\\\/litespeed\\\/avatar\\\/ba00c276ce0fa7863cda4038d70907a8.jpg?ver=1784037436\",\"contentUrl\":\"https:\\\/\\\/focolares.es\\\/wp-content\\\/litespeed\\\/avatar\\\/ba00c276ce0fa7863cda4038d70907a8.jpg?ver=1784037436\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/focolares.es\"],\"url\":\"https:\\\/\\\/focolares.es\\\/gl\\\/author\\\/afesersl_mcjhk9wv\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Proximidade e Liberdade - Movemento dos Focolares","description":"Entrevista ao presidente do Movemento dos Focolares, realizada por Peter Forst para a revista Neue Stadt sobre o tema do ano: a proximidade.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/focolares.es\/gl\/proximidade-e-liberdade\/","og_locale":"gl_ES","og_type":"article","og_title":"Proximidad y libertad - Movimiento de los Focolares","og_description":"Entrevista a la presidenta de los Focolares, realizada por Peter Forst para la revista Neue Stadt sobre el tema del a\u00f1o: la proximidad.","og_url":"https:\/\/focolares.es\/gl\/proximidade-e-liberdade\/","og_site_name":"Movimiento de los Focolares","article_published_time":"2025-02-24T17:07:00+00:00","article_modified_time":"2025-03-27T20:24:19+00:00","og_image":[{"width":800,"height":500,"url":"https:\/\/focolares.es\/wp-content\/uploads\/2025\/02\/Margaret-DSC00871-400x250-1.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tempo de lectura":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/focolares.es\/proximidad-y-libertad\/#article","isPartOf":{"@id":"https:\/\/focolares.es\/proximidad-y-libertad\/"},"author":{"name":"admin","@id":"https:\/\/focolares.es\/#\/schema\/person\/fdbf1cac3e3957f836bf607a31e7616d"},"headline":"Proximidad y libertad","datePublished":"2025-02-24T17:07:00+00:00","dateModified":"2025-03-27T20:24:19+00:00","mainEntityOfPage":{"@id":"https:\/\/focolares.es\/proximidad-y-libertad\/"},"wordCount":1643,"commentCount":0,"publisher":{"@id":"https:\/\/focolares.es\/#organization"},"image":{"@id":"https:\/\/focolares.es\/proximidad-y-libertad\/#primaryimage"},"thumbnailUrl":"https:\/\/focolares.es\/wp-content\/uploads\/2025\/02\/Margaret-DSC00871-400x250-1.jpg","keywords":["Entrevista"],"articleSection":["Uncategorized"],"inLanguage":"gl-ES","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/focolares.es\/proximidad-y-libertad\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/focolares.es\/proximidad-y-libertad\/","url":"https:\/\/focolares.es\/proximidad-y-libertad\/","name":"Proximidade e Liberdade - Movemento dos Focolares","isPartOf":{"@id":"https:\/\/focolares.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/focolares.es\/proximidad-y-libertad\/#primaryimage"},"image":{"@id":"https:\/\/focolares.es\/proximidad-y-libertad\/#primaryimage"},"thumbnailUrl":"https:\/\/focolares.es\/wp-content\/uploads\/2025\/02\/Margaret-DSC00871-400x250-1.jpg","datePublished":"2025-02-24T17:07:00+00:00","dateModified":"2025-03-27T20:24:19+00:00","description":"Entrevista ao presidente do Movemento dos Focolares, realizada por Peter Forst para a revista Neue Stadt sobre o tema do ano: a proximidade.","breadcrumb":{"@id":"https:\/\/focolares.es\/proximidad-y-libertad\/#breadcrumb"},"inLanguage":"gl-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/focolares.es\/proximidad-y-libertad\/"]}]},{"@type":"ImageObject","inLanguage":"gl-ES","@id":"https:\/\/focolares.es\/proximidad-y-libertad\/#primaryimage","url":"https:\/\/focolares.es\/wp-content\/uploads\/2025\/02\/Margaret-DSC00871-400x250-1.jpg","contentUrl":"https:\/\/focolares.es\/wp-content\/uploads\/2025\/02\/Margaret-DSC00871-400x250-1.jpg","width":800,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/focolares.es\/proximidad-y-libertad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/focolares.es\/"},{"@type":"ListItem","position":2,"name":"Proximidad y libertad"}]},{"@type":"WebSite","@id":"https:\/\/focolares.es\/#website","url":"https:\/\/focolares.es\/","name":"Movemento dos Focolares","description":"","publisher":{"@id":"https:\/\/focolares.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/focolares.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"gl-ES"},{"@type":"Organization","@id":"https:\/\/focolares.es\/#organization","name":"Movemento dos Focolares","url":"https:\/\/focolares.es\/","logo":{"@type":"ImageObject","inLanguage":"gl-ES","@id":"https:\/\/focolares.es\/#\/schema\/logo\/image\/","url":"https:\/\/focolares.es\/wp-content\/uploads\/2024\/03\/Logo_focolares-1024x944-1.jpg","contentUrl":"https:\/\/focolares.es\/wp-content\/uploads\/2024\/03\/Logo_focolares-1024x944-1.jpg","width":1024,"height":944,"caption":"Movimiento de los Focolares"},"image":{"@id":"https:\/\/focolares.es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/focolares.es\/#\/schema\/person\/fdbf1cac3e3957f836bf607a31e7616d","name":"administrador","image":{"@type":"ImageObject","inLanguage":"gl-ES","@id":"https:\/\/focolares.es\/wp-content\/litespeed\/avatar\/ba00c276ce0fa7863cda4038d70907a8.jpg?ver=1784037436","url":"https:\/\/focolares.es\/wp-content\/litespeed\/avatar\/ba00c276ce0fa7863cda4038d70907a8.jpg?ver=1784037436","contentUrl":"https:\/\/focolares.es\/wp-content\/litespeed\/avatar\/ba00c276ce0fa7863cda4038d70907a8.jpg?ver=1784037436","caption":"admin"},"sameAs":["https:\/\/focolares.es"],"url":"https:\/\/focolares.es\/gl\/author\/afesersl_mcjhk9wv\/"}]}},"views":135,"_links":{"self":[{"href":"https:\/\/focolares.es\/gl\/wp-json\/wp\/v2\/posts\/15312","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/focolares.es\/gl\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/focolares.es\/gl\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/focolares.es\/gl\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/focolares.es\/gl\/wp-json\/wp\/v2\/comments?post=15312"}],"version-history":[{"count":6,"href":"https:\/\/focolares.es\/gl\/wp-json\/wp\/v2\/posts\/15312\/revisions"}],"predecessor-version":[{"id":15722,"href":"https:\/\/focolares.es\/gl\/wp-json\/wp\/v2\/posts\/15312\/revisions\/15722"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/focolares.es\/gl\/wp-json\/wp\/v2\/media\/15402"}],"wp:attachment":[{"href":"https:\/\/focolares.es\/gl\/wp-json\/wp\/v2\/media?parent=15312"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/focolares.es\/gl\/wp-json\/wp\/v2\/categories?post=15312"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/focolares.es\/gl\/wp-json\/wp\/v2\/tags?post=15312"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}