{"id":15466,"date":"2025-02-15T14:38:00","date_gmt":"2025-02-15T13:38:00","guid":{"rendered":"https:\/\/focolares.es\/?p=15466"},"modified":"2025-03-05T14:02:11","modified_gmt":"2025-03-05T13:02:11","slug":"manifesto-pola-fraternidade","status":"publish","type":"post","link":"https:\/\/focolares.es\/gl\/manifiesto-por-la-fraternidad\/","title":{"rendered":"Manifesto pola Fraternidade"},"content":{"rendered":"<h4 class=\"wp-block-heading\"><strong><em>&quot;Calquera que, en solitario, se propo\u00f1a hoxe mover as monta\u00f1as da indiferenza, o odio e a violencia ten unha tarefa enorme. Pero o que pode ser imposible para mill\u00f3ns de persoas illadas e afastadas pode ser posible para persoas que fixeron da fraternidade universal a motivaci\u00f3n esencial das s\u00faas vidas&quot;.<\/em><\/strong><\/h4>\n\n\n\n<div class=\"wp-block-media-text is-stacked-on-mobile\" style=\"grid-template-columns:32% auto\"><figure class=\"wp-block-media-text__media\"><img fetchpriority=\"high\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/focolares.es\/wp-content\/uploads\/2025\/03\/Dia-Fraternidad-300x300-1.png\" alt=\"\" class=\"wp-image-15468 size-full\" srcset=\"https:\/\/focolares.es\/wp-content\/uploads\/2025\/03\/Dia-Fraternidad-300x300-1.png 300w, https:\/\/focolares.es\/wp-content\/uploads\/2025\/03\/Dia-Fraternidad-300x300-1-150x150.png 150w, https:\/\/focolares.es\/wp-content\/uploads\/2025\/03\/Dia-Fraternidad-300x300-1-12x12.png 12w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p>Estas palabras de&nbsp;<strong>Chiara Lubich<\/strong>, na s\u00faa intervenci\u00f3n ante o&nbsp;<strong>Parlamento Europeo<\/strong>&nbsp;na sesi\u00f3n do 15 de setembro de 1998, son as inspiraci\u00f3ns para, o&nbsp;<a href=\"https:\/\/ciudadesporlafraternidad.blogspot.com\/\" target=\"_blank\" rel=\"noreferrer noopener\"><em>Asociaci\u00f3n Cidades pola Fraternidade<\/em><\/a>, dos principios sobre os que desenvolve a s\u00faa actividade. O seu presidente,&nbsp;<strong>Pilar Ferrero,<\/strong>&nbsp;Expl\u00edcao brevemente no v\u00eddeo que se pode ver na ligaz\u00f3n anterior.<\/p>\n<\/div><\/div>\n\n\n\n<p>Con motivo da celebraci\u00f3n, \u00faltimo&nbsp;<strong>4 de febreiro de 2025<\/strong>, do&nbsp;<a href=\"https:\/\/www.un.org\/es\/observances\/human-fraternity\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>D\u00eda Internacional da Fraternidade Humana<\/strong><\/a>, o&nbsp;<em>Asociaci\u00f3n Cidades pola Fraternidade<\/em>&nbsp;desenvolvido a&nbsp;<strong>Manifesto pola fraternidade,&nbsp;<\/strong>cuxo texto se presenta a continuaci\u00f3n:<\/p>\n\n\n\n<p>A resoluci\u00f3n 75\/200 da ONU establece que a fraternidade humana \u00e9 un concepto que enfatiza a conexi\u00f3n e a solidariedade entre todos os seres humanos, independentemente das s\u00faas diferenzas culturais, relixiosas, \u00e9tnicas, pol\u00edticas ou sociais. Bas\u00e9ase na idea de que todos os seres humanos comparten unha dignidade e un valor inherentes simplemente por pertencer \u00e1 humanidade.<\/p>\n\n\n\n<p>Dende a pertenza \u00e1 gran familia humana, situ\u00e1monos nun lugar concreto onde vivimos e interactuamos: a cidade. A fraternidade permite a introduci\u00f3n de novos principios na acci\u00f3n pol\u00edtica coti\u00e1; Por iso, \u00e9 importante a presenza dos Concellos como socios.<\/p>\n\n\n\n<p>Os gobernos locais comprom\u00e9tense a incorporar a fraternidade como parte do seu proxecto pol\u00edtico, procurando que nunca gobernen contra ningu\u00e9n, non s\u00f3 como expresi\u00f3n dun sector da cidadan\u00eda, sen\u00f3n de todos os cidad\u00e1ns.<\/p>\n\n\n\n<p><strong>A fraternidade non \u00e9 un \u201ccomplemento\u201d da pol\u00edtica, sen\u00f3n a s\u00faa esencia<\/strong>, e haber\u00eda que definir os m\u00e9todos e obxectivos deste \u00faltimo; S\u00f3 colocando a fraternidade na s\u00faa categor\u00eda aut\u00e9ntica a pol\u00edtica adquire o seu verdadeiro sentido: sobre todo o servizo \u00e1 comunidade, co cidad\u00e1n como suxeito activo.<\/p>\n\n\n\n<p>Chiara Lubich, fundadora da <em>Movemento dos Focolares<\/em>, afirmou no Parlamento Europeo (sesi\u00f3n do 15 de setembro de 1998): <em>&quot;Calquera que, en solitario, se propo\u00f1a hoxe mover as monta\u00f1as da indiferenza, o odio e a violencia ten unha tarefa enorme por diante. Pero o que pode ser imposible para mill\u00f3ns de homes illados e afastados, pode ser posible para as persoas que fixeron da fraternidade universal a motivaci\u00f3n esencial das s\u00faas vidas.<\/em>.<\/p>\n\n\n\n<p>Estas palabras inspiradoras poden axudar a acadar os obxectivos dunha experiencia de compromiso co di\u00e1logo e a creaci\u00f3n dunha rede aberta de concellos e outras entidades locais e rexionais, na que participen cidad\u00e1ns activos, pol\u00edticos militantes de diversos partidos e movementos pol\u00edticos, cargos p\u00fablicos e asociaci\u00f3ns interesadas na vida da cidade e que busquen crear un espazo de traballo permanente para experiencias positivas que se poidan conectar e multiplicar, onde se manifesten ante todo a xustiza social, a paz, a fraternidade e os dereitos humanos.<\/p>\n\n\n\n<p class=\"has-text-align-right\"><em>Asociaci\u00f3n Cidades pola Fraternidade<\/em><br><em>4 de febreiro de 2025<\/em><\/p>\n\n\n\n<hr class=\"wp-block-separator has-text-color has-alpha-channel-opacity has-background\" style=\"background-color:#dddddd;color:#dddddd\"\/>\n\n\n\n<p><a href=\"https:\/\/focolares.es\/wp-content\/uploads\/2025\/03\/MANIFIESTO-POR-LA-FRATERNIDAD_C.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Descarga o manifesto<\/a><\/p>\n\n\n\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Manifesto pola Fraternidade con motivo da celebraci\u00f3n, o 4 de febreiro de 2025, do D\u00eda Internacional da Fraternidade Humana.<\/p>","protected":false},"author":8,"featured_media":15467,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"footnotes":""},"categories":[1],"tags":[42],"class_list":["post-15466","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized","tag-comunicado"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Manifiesto por la Fraternidad - Movimiento de los Focolares<\/title>\n<meta name=\"description\" content=\"Manifiesto por la Fraternidad con ocasi\u00f3n de la celebraci\u00f3n, el pasado 4 de febrero de 2025, del D\u00eda Internacional de la Fraternidad Humana.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/focolares.es\/gl\/manifesto-pola-fraternidade\/\" \/>\n<meta property=\"og:locale\" content=\"gl_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Manifiesto por la Fraternidad - Movimiento de los Focolares\" \/>\n<meta property=\"og:description\" content=\"Manifiesto por la Fraternidad con ocasi\u00f3n de la celebraci\u00f3n, el pasado 4 de febrero de 2025, del D\u00eda Internacional de la Fraternidad Humana.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/focolares.es\/gl\/manifesto-pola-fraternidade\/\" \/>\n<meta property=\"og:site_name\" content=\"Movimiento de los Focolares\" \/>\n<meta property=\"article:published_time\" content=\"2025-02-15T13:38:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-05T13:02:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/focolares.es\/wp-content\/uploads\/2025\/03\/Ciudades-Fraternidad-300x200-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"169\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Sonia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sonia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/focolares.es\\\/manifiesto-por-la-fraternidad\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/focolares.es\\\/manifiesto-por-la-fraternidad\\\/\"},\"author\":{\"name\":\"Sonia\",\"@id\":\"https:\\\/\\\/focolares.es\\\/#\\\/schema\\\/person\\\/460a502493de84fa7b318667e9a5c289\"},\"headline\":\"Manifiesto por la Fraternidad\",\"datePublished\":\"2025-02-15T13:38:00+00:00\",\"dateModified\":\"2025-03-05T13:02:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/focolares.es\\\/manifiesto-por-la-fraternidad\\\/\"},\"wordCount\":577,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/focolares.es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/focolares.es\\\/manifiesto-por-la-fraternidad\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/focolares.es\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Ciudades-Fraternidad-300x200-1.png\",\"keywords\":[\"Comunicado\"],\"articleSection\":[\"Uncategorized\"],\"inLanguage\":\"gl-ES\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/focolares.es\\\/manifiesto-por-la-fraternidad\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/focolares.es\\\/manifiesto-por-la-fraternidad\\\/\",\"url\":\"https:\\\/\\\/focolares.es\\\/manifiesto-por-la-fraternidad\\\/\",\"name\":\"Manifiesto por la Fraternidad - Movimiento de los Focolares\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/focolares.es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/focolares.es\\\/manifiesto-por-la-fraternidad\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/focolares.es\\\/manifiesto-por-la-fraternidad\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/focolares.es\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Ciudades-Fraternidad-300x200-1.png\",\"datePublished\":\"2025-02-15T13:38:00+00:00\",\"dateModified\":\"2025-03-05T13:02:11+00:00\",\"description\":\"Manifiesto por la Fraternidad con ocasi\u00f3n de la celebraci\u00f3n, el pasado 4 de febrero de 2025, del D\u00eda Internacional de la Fraternidad Humana.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/focolares.es\\\/manifiesto-por-la-fraternidad\\\/#breadcrumb\"},\"inLanguage\":\"gl-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/focolares.es\\\/manifiesto-por-la-fraternidad\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"gl-ES\",\"@id\":\"https:\\\/\\\/focolares.es\\\/manifiesto-por-la-fraternidad\\\/#primaryimage\",\"url\":\"https:\\\/\\\/focolares.es\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Ciudades-Fraternidad-300x200-1.png\",\"contentUrl\":\"https:\\\/\\\/focolares.es\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Ciudades-Fraternidad-300x200-1.png\",\"width\":300,\"height\":169},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/focolares.es\\\/manifiesto-por-la-fraternidad\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/focolares.es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Manifiesto por la Fraternidad\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/focolares.es\\\/#website\",\"url\":\"https:\\\/\\\/focolares.es\\\/\",\"name\":\"Movimiento de los Focolares\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/focolares.es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/focolares.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"gl-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/focolares.es\\\/#organization\",\"name\":\"Movimiento de los Focolares\",\"url\":\"https:\\\/\\\/focolares.es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"gl-ES\",\"@id\":\"https:\\\/\\\/focolares.es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/focolares.es\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Logo_focolares-1024x944-1.jpg\",\"contentUrl\":\"https:\\\/\\\/focolares.es\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Logo_focolares-1024x944-1.jpg\",\"width\":1024,\"height\":944,\"caption\":\"Movimiento de los Focolares\"},\"image\":{\"@id\":\"https:\\\/\\\/focolares.es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/focolares.es\\\/#\\\/schema\\\/person\\\/460a502493de84fa7b318667e9a5c289\",\"name\":\"Sonia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"gl-ES\",\"@id\":\"https:\\\/\\\/focolares.es\\\/wp-content\\\/litespeed\\\/avatar\\\/cdad09e33a37c7312cdc76ceae4bbc88.jpg?ver=1784032935\",\"url\":\"https:\\\/\\\/focolares.es\\\/wp-content\\\/litespeed\\\/avatar\\\/cdad09e33a37c7312cdc76ceae4bbc88.jpg?ver=1784032935\",\"contentUrl\":\"https:\\\/\\\/focolares.es\\\/wp-content\\\/litespeed\\\/avatar\\\/cdad09e33a37c7312cdc76ceae4bbc88.jpg?ver=1784032935\",\"caption\":\"Sonia\"},\"url\":\"https:\\\/\\\/focolares.es\\\/gl\\\/author\\\/sonia\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Manifesto pola Fraternidade - Movemento dos Focolares","description":"Manifesto pola Fraternidade con motivo da celebraci\u00f3n, o 4 de febreiro de 2025, do D\u00eda Internacional da Fraternidade Humana.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/focolares.es\/gl\/manifesto-pola-fraternidade\/","og_locale":"gl_ES","og_type":"article","og_title":"Manifiesto por la Fraternidad - Movimiento de los Focolares","og_description":"Manifiesto por la Fraternidad con ocasi\u00f3n de la celebraci\u00f3n, el pasado 4 de febrero de 2025, del D\u00eda Internacional de la Fraternidad Humana.","og_url":"https:\/\/focolares.es\/gl\/manifesto-pola-fraternidade\/","og_site_name":"Movimiento de los Focolares","article_published_time":"2025-02-15T13:38:00+00:00","article_modified_time":"2025-03-05T13:02:11+00:00","og_image":[{"width":300,"height":169,"url":"https:\/\/focolares.es\/wp-content\/uploads\/2025\/03\/Ciudades-Fraternidad-300x200-1.png","type":"image\/png"}],"author":"Sonia","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Sonia","Tempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/focolares.es\/manifiesto-por-la-fraternidad\/#article","isPartOf":{"@id":"https:\/\/focolares.es\/manifiesto-por-la-fraternidad\/"},"author":{"name":"Sonia","@id":"https:\/\/focolares.es\/#\/schema\/person\/460a502493de84fa7b318667e9a5c289"},"headline":"Manifiesto por la Fraternidad","datePublished":"2025-02-15T13:38:00+00:00","dateModified":"2025-03-05T13:02:11+00:00","mainEntityOfPage":{"@id":"https:\/\/focolares.es\/manifiesto-por-la-fraternidad\/"},"wordCount":577,"commentCount":0,"publisher":{"@id":"https:\/\/focolares.es\/#organization"},"image":{"@id":"https:\/\/focolares.es\/manifiesto-por-la-fraternidad\/#primaryimage"},"thumbnailUrl":"https:\/\/focolares.es\/wp-content\/uploads\/2025\/03\/Ciudades-Fraternidad-300x200-1.png","keywords":["Comunicado"],"articleSection":["Uncategorized"],"inLanguage":"gl-ES","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/focolares.es\/manifiesto-por-la-fraternidad\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/focolares.es\/manifiesto-por-la-fraternidad\/","url":"https:\/\/focolares.es\/manifiesto-por-la-fraternidad\/","name":"Manifesto pola Fraternidade - Movemento dos Focolares","isPartOf":{"@id":"https:\/\/focolares.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/focolares.es\/manifiesto-por-la-fraternidad\/#primaryimage"},"image":{"@id":"https:\/\/focolares.es\/manifiesto-por-la-fraternidad\/#primaryimage"},"thumbnailUrl":"https:\/\/focolares.es\/wp-content\/uploads\/2025\/03\/Ciudades-Fraternidad-300x200-1.png","datePublished":"2025-02-15T13:38:00+00:00","dateModified":"2025-03-05T13:02:11+00:00","description":"Manifesto pola Fraternidade con motivo da celebraci\u00f3n, o 4 de febreiro de 2025, do D\u00eda Internacional da Fraternidade Humana.","breadcrumb":{"@id":"https:\/\/focolares.es\/manifiesto-por-la-fraternidad\/#breadcrumb"},"inLanguage":"gl-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/focolares.es\/manifiesto-por-la-fraternidad\/"]}]},{"@type":"ImageObject","inLanguage":"gl-ES","@id":"https:\/\/focolares.es\/manifiesto-por-la-fraternidad\/#primaryimage","url":"https:\/\/focolares.es\/wp-content\/uploads\/2025\/03\/Ciudades-Fraternidad-300x200-1.png","contentUrl":"https:\/\/focolares.es\/wp-content\/uploads\/2025\/03\/Ciudades-Fraternidad-300x200-1.png","width":300,"height":169},{"@type":"BreadcrumbList","@id":"https:\/\/focolares.es\/manifiesto-por-la-fraternidad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/focolares.es\/"},{"@type":"ListItem","position":2,"name":"Manifiesto por la Fraternidad"}]},{"@type":"WebSite","@id":"https:\/\/focolares.es\/#website","url":"https:\/\/focolares.es\/","name":"Movemento dos Focolares","description":"","publisher":{"@id":"https:\/\/focolares.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/focolares.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"gl-ES"},{"@type":"Organization","@id":"https:\/\/focolares.es\/#organization","name":"Movemento dos Focolares","url":"https:\/\/focolares.es\/","logo":{"@type":"ImageObject","inLanguage":"gl-ES","@id":"https:\/\/focolares.es\/#\/schema\/logo\/image\/","url":"https:\/\/focolares.es\/wp-content\/uploads\/2024\/03\/Logo_focolares-1024x944-1.jpg","contentUrl":"https:\/\/focolares.es\/wp-content\/uploads\/2024\/03\/Logo_focolares-1024x944-1.jpg","width":1024,"height":944,"caption":"Movimiento de los Focolares"},"image":{"@id":"https:\/\/focolares.es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/focolares.es\/#\/schema\/person\/460a502493de84fa7b318667e9a5c289","name":"Sonia","image":{"@type":"ImageObject","inLanguage":"gl-ES","@id":"https:\/\/focolares.es\/wp-content\/litespeed\/avatar\/cdad09e33a37c7312cdc76ceae4bbc88.jpg?ver=1784032935","url":"https:\/\/focolares.es\/wp-content\/litespeed\/avatar\/cdad09e33a37c7312cdc76ceae4bbc88.jpg?ver=1784032935","contentUrl":"https:\/\/focolares.es\/wp-content\/litespeed\/avatar\/cdad09e33a37c7312cdc76ceae4bbc88.jpg?ver=1784032935","caption":"Sonia"},"url":"https:\/\/focolares.es\/gl\/author\/sonia\/"}]}},"views":96,"_links":{"self":[{"href":"https:\/\/focolares.es\/gl\/wp-json\/wp\/v2\/posts\/15466","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/focolares.es\/gl\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/focolares.es\/gl\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/focolares.es\/gl\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/focolares.es\/gl\/wp-json\/wp\/v2\/comments?post=15466"}],"version-history":[{"count":10,"href":"https:\/\/focolares.es\/gl\/wp-json\/wp\/v2\/posts\/15466\/revisions"}],"predecessor-version":[{"id":15533,"href":"https:\/\/focolares.es\/gl\/wp-json\/wp\/v2\/posts\/15466\/revisions\/15533"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/focolares.es\/gl\/wp-json\/wp\/v2\/media\/15467"}],"wp:attachment":[{"href":"https:\/\/focolares.es\/gl\/wp-json\/wp\/v2\/media?parent=15466"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/focolares.es\/gl\/wp-json\/wp\/v2\/categories?post=15466"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/focolares.es\/gl\/wp-json\/wp\/v2\/tags?post=15466"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}