{"id":15478,"date":"2025-03-02T18:48:42","date_gmt":"2025-03-02T17:48:42","guid":{"rendered":"https:\/\/focolares.es\/?p=15478"},"modified":"2025-03-06T19:01:05","modified_gmt":"2025-03-06T18:01:05","slug":"querido-papa-francisco","status":"publish","type":"post","link":"https:\/\/focolares.es\/gl\/querido-papa-francisco\/","title":{"rendered":"Na oraci\u00f3n polo Papa Francisco"},"content":{"rendered":"<h4 class=\"wp-block-heading\"><em>O Movemento dos Focolares \u00fanese na oraci\u00f3n pola sa\u00fade do Santo Pai.<\/em><\/h4>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-media-text is-stacked-on-mobile\"><figure class=\"wp-block-media-text__media\"><img fetchpriority=\"high\" decoding=\"async\" width=\"441\" height=\"248\" src=\"https:\/\/focolares.es\/wp-content\/uploads\/2025\/03\/PapaFrancisco_1.jpg\" alt=\"\" class=\"wp-image-15537 size-full\" srcset=\"https:\/\/focolares.es\/wp-content\/uploads\/2025\/03\/PapaFrancisco_1.jpg 441w, https:\/\/focolares.es\/wp-content\/uploads\/2025\/03\/PapaFrancisco_1-300x169.jpg 300w, https:\/\/focolares.es\/wp-content\/uploads\/2025\/03\/PapaFrancisco_1-18x10.jpg 18w\" sizes=\"(max-width: 441px) 100vw, 441px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p>A presidenta do Movemento dos Focolares, Margaret Karram, enviou unha mensaxe ao Santo Pai garantindolle a s\u00faa afectuosa proximidade e as s\u00faas fervorosas oraci\u00f3ns.<\/p>\n<\/div><\/div>\n<\/div>\n<\/div>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p><em>&quot;P\u00eddolle \u00e1 Virxe que che faga sentir o seu amor materno e esa tenrura que sempre nos recomendas ter polo ben de cada veci\u00f1o e de cada pobo&quot;.<\/em>, escribiu o presidente.<br><em>&quot;Infinitamente agradecido pola s\u00faa vida completamente dedicada a Deus e ao ben da humanidade&quot;.<\/em>\u00a0-pato-\u00a0<em>&quot;Env\u00edovos o abrazo de todo o Movemento dos Focolares por todo o mundo, que reza constantemente e ofrece as s\u00faas oraci\u00f3ns por v\u00f3s&quot;.<\/em>.<\/p>\n<\/blockquote>\n\n\n\n<p>A web internacional dos Focolares publicou o\u00a0<a href=\"https:\/\/www.focolare.org\/es\/querido-papa-francisco\/\" target=\"_blank\" rel=\"noreferrer noopener\">Testemu\u00f1o de Luciana Scalacci<\/a>, un non crente que asegura ao Papa que &quot;nunca deixo de pensar e rezar por ti secularmente. Por favor, rece por min de xeito cristi\u00e1n&quot;.<\/p>\n\n\n\n<p>En Espa\u00f1a, membros do movemento dos Focolares tam\u00e9n rezan e ofrecen pola recuperaci\u00f3n do Papa, apoiando as distintas iniciativas propostas tanto polo Vaticano como polas igrexas locais.<\/p>\n\n\n\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>O Movemento dos Focolares \u00fanese na oraci\u00f3n pola sa\u00fade do Santo Pai.<\/p>","protected":false},"author":8,"featured_media":15537,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"footnotes":""},"categories":[1],"tags":[40],"class_list":["post-15478","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized","tag-dialogo-y-fraternidad"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>En oraci\u00f3n por el Papa Francisco - Focolares<\/title>\n<meta name=\"description\" content=\"El Movimiento de los Focolares se une en oraci\u00f3n por la salud del Santo Padre.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/focolares.es\/gl\/querido-papa-francisco\/\" \/>\n<meta property=\"og:locale\" content=\"gl_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"En oraci\u00f3n por el Papa Francisco - Focolares\" \/>\n<meta property=\"og:description\" content=\"El Movimiento de los Focolares se une en oraci\u00f3n por la salud del Santo Padre.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/focolares.es\/gl\/querido-papa-francisco\/\" \/>\n<meta property=\"og:site_name\" content=\"Movimiento de los Focolares\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-02T17:48:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-06T18:01:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/focolares.es\/wp-content\/uploads\/2025\/03\/PapaFrancisco_1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"441\" \/>\n\t<meta property=\"og:image:height\" content=\"248\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Sonia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sonia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/focolares.es\\\/querido-papa-francisco\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/focolares.es\\\/querido-papa-francisco\\\/\"},\"author\":{\"name\":\"Sonia\",\"@id\":\"https:\\\/\\\/focolares.es\\\/#\\\/schema\\\/person\\\/460a502493de84fa7b318667e9a5c289\"},\"headline\":\"En oraci\u00f3n por el Papa Francisco\",\"datePublished\":\"2025-03-02T17:48:42+00:00\",\"dateModified\":\"2025-03-06T18:01:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/focolares.es\\\/querido-papa-francisco\\\/\"},\"wordCount\":198,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/focolares.es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/focolares.es\\\/querido-papa-francisco\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/focolares.es\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/PapaFrancisco_1.jpg\",\"keywords\":[\"Di\u00e1logo y fraternidad\"],\"articleSection\":[\"Uncategorized\"],\"inLanguage\":\"gl-ES\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/focolares.es\\\/querido-papa-francisco\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/focolares.es\\\/querido-papa-francisco\\\/\",\"url\":\"https:\\\/\\\/focolares.es\\\/querido-papa-francisco\\\/\",\"name\":\"En oraci\u00f3n por el Papa Francisco - Focolares\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/focolares.es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/focolares.es\\\/querido-papa-francisco\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/focolares.es\\\/querido-papa-francisco\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/focolares.es\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/PapaFrancisco_1.jpg\",\"datePublished\":\"2025-03-02T17:48:42+00:00\",\"dateModified\":\"2025-03-06T18:01:05+00:00\",\"description\":\"El Movimiento de los Focolares se une en oraci\u00f3n por la salud del Santo Padre.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/focolares.es\\\/querido-papa-francisco\\\/#breadcrumb\"},\"inLanguage\":\"gl-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/focolares.es\\\/querido-papa-francisco\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"gl-ES\",\"@id\":\"https:\\\/\\\/focolares.es\\\/querido-papa-francisco\\\/#primaryimage\",\"url\":\"https:\\\/\\\/focolares.es\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/PapaFrancisco_1.jpg\",\"contentUrl\":\"https:\\\/\\\/focolares.es\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/PapaFrancisco_1.jpg\",\"width\":441,\"height\":248},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/focolares.es\\\/querido-papa-francisco\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/focolares.es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"En oraci\u00f3n por el Papa Francisco\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/focolares.es\\\/#website\",\"url\":\"https:\\\/\\\/focolares.es\\\/\",\"name\":\"Movimiento de los Focolares\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/focolares.es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/focolares.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"gl-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/focolares.es\\\/#organization\",\"name\":\"Movimiento de los Focolares\",\"url\":\"https:\\\/\\\/focolares.es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"gl-ES\",\"@id\":\"https:\\\/\\\/focolares.es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/focolares.es\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Logo_focolares-1024x944-1.jpg\",\"contentUrl\":\"https:\\\/\\\/focolares.es\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Logo_focolares-1024x944-1.jpg\",\"width\":1024,\"height\":944,\"caption\":\"Movimiento de los Focolares\"},\"image\":{\"@id\":\"https:\\\/\\\/focolares.es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/focolares.es\\\/#\\\/schema\\\/person\\\/460a502493de84fa7b318667e9a5c289\",\"name\":\"Sonia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"gl-ES\",\"@id\":\"https:\\\/\\\/focolares.es\\\/wp-content\\\/litespeed\\\/avatar\\\/cdad09e33a37c7312cdc76ceae4bbc88.jpg?ver=1784032935\",\"url\":\"https:\\\/\\\/focolares.es\\\/wp-content\\\/litespeed\\\/avatar\\\/cdad09e33a37c7312cdc76ceae4bbc88.jpg?ver=1784032935\",\"contentUrl\":\"https:\\\/\\\/focolares.es\\\/wp-content\\\/litespeed\\\/avatar\\\/cdad09e33a37c7312cdc76ceae4bbc88.jpg?ver=1784032935\",\"caption\":\"Sonia\"},\"url\":\"https:\\\/\\\/focolares.es\\\/gl\\\/author\\\/sonia\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Na oraci\u00f3n polo Papa Francisco - Focolares","description":"O Movemento dos Focolares \u00fanese na oraci\u00f3n pola sa\u00fade do Santo Pai.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/focolares.es\/gl\/querido-papa-francisco\/","og_locale":"gl_ES","og_type":"article","og_title":"En oraci\u00f3n por el Papa Francisco - Focolares","og_description":"El Movimiento de los Focolares se une en oraci\u00f3n por la salud del Santo Padre.","og_url":"https:\/\/focolares.es\/gl\/querido-papa-francisco\/","og_site_name":"Movimiento de los Focolares","article_published_time":"2025-03-02T17:48:42+00:00","article_modified_time":"2025-03-06T18:01:05+00:00","og_image":[{"width":441,"height":248,"url":"https:\/\/focolares.es\/wp-content\/uploads\/2025\/03\/PapaFrancisco_1.jpg","type":"image\/jpeg"}],"author":"Sonia","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Sonia","Tempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/focolares.es\/querido-papa-francisco\/#article","isPartOf":{"@id":"https:\/\/focolares.es\/querido-papa-francisco\/"},"author":{"name":"Sonia","@id":"https:\/\/focolares.es\/#\/schema\/person\/460a502493de84fa7b318667e9a5c289"},"headline":"En oraci\u00f3n por el Papa Francisco","datePublished":"2025-03-02T17:48:42+00:00","dateModified":"2025-03-06T18:01:05+00:00","mainEntityOfPage":{"@id":"https:\/\/focolares.es\/querido-papa-francisco\/"},"wordCount":198,"commentCount":0,"publisher":{"@id":"https:\/\/focolares.es\/#organization"},"image":{"@id":"https:\/\/focolares.es\/querido-papa-francisco\/#primaryimage"},"thumbnailUrl":"https:\/\/focolares.es\/wp-content\/uploads\/2025\/03\/PapaFrancisco_1.jpg","keywords":["Di\u00e1logo y fraternidad"],"articleSection":["Uncategorized"],"inLanguage":"gl-ES","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/focolares.es\/querido-papa-francisco\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/focolares.es\/querido-papa-francisco\/","url":"https:\/\/focolares.es\/querido-papa-francisco\/","name":"Na oraci\u00f3n polo Papa Francisco - Focolares","isPartOf":{"@id":"https:\/\/focolares.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/focolares.es\/querido-papa-francisco\/#primaryimage"},"image":{"@id":"https:\/\/focolares.es\/querido-papa-francisco\/#primaryimage"},"thumbnailUrl":"https:\/\/focolares.es\/wp-content\/uploads\/2025\/03\/PapaFrancisco_1.jpg","datePublished":"2025-03-02T17:48:42+00:00","dateModified":"2025-03-06T18:01:05+00:00","description":"O Movemento dos Focolares \u00fanese na oraci\u00f3n pola sa\u00fade do Santo Pai.","breadcrumb":{"@id":"https:\/\/focolares.es\/querido-papa-francisco\/#breadcrumb"},"inLanguage":"gl-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/focolares.es\/querido-papa-francisco\/"]}]},{"@type":"ImageObject","inLanguage":"gl-ES","@id":"https:\/\/focolares.es\/querido-papa-francisco\/#primaryimage","url":"https:\/\/focolares.es\/wp-content\/uploads\/2025\/03\/PapaFrancisco_1.jpg","contentUrl":"https:\/\/focolares.es\/wp-content\/uploads\/2025\/03\/PapaFrancisco_1.jpg","width":441,"height":248},{"@type":"BreadcrumbList","@id":"https:\/\/focolares.es\/querido-papa-francisco\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/focolares.es\/"},{"@type":"ListItem","position":2,"name":"En oraci\u00f3n por el Papa Francisco"}]},{"@type":"WebSite","@id":"https:\/\/focolares.es\/#website","url":"https:\/\/focolares.es\/","name":"Movemento dos Focolares","description":"","publisher":{"@id":"https:\/\/focolares.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/focolares.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"gl-ES"},{"@type":"Organization","@id":"https:\/\/focolares.es\/#organization","name":"Movemento dos Focolares","url":"https:\/\/focolares.es\/","logo":{"@type":"ImageObject","inLanguage":"gl-ES","@id":"https:\/\/focolares.es\/#\/schema\/logo\/image\/","url":"https:\/\/focolares.es\/wp-content\/uploads\/2024\/03\/Logo_focolares-1024x944-1.jpg","contentUrl":"https:\/\/focolares.es\/wp-content\/uploads\/2024\/03\/Logo_focolares-1024x944-1.jpg","width":1024,"height":944,"caption":"Movimiento de los Focolares"},"image":{"@id":"https:\/\/focolares.es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/focolares.es\/#\/schema\/person\/460a502493de84fa7b318667e9a5c289","name":"Sonia","image":{"@type":"ImageObject","inLanguage":"gl-ES","@id":"https:\/\/focolares.es\/wp-content\/litespeed\/avatar\/cdad09e33a37c7312cdc76ceae4bbc88.jpg?ver=1784032935","url":"https:\/\/focolares.es\/wp-content\/litespeed\/avatar\/cdad09e33a37c7312cdc76ceae4bbc88.jpg?ver=1784032935","contentUrl":"https:\/\/focolares.es\/wp-content\/litespeed\/avatar\/cdad09e33a37c7312cdc76ceae4bbc88.jpg?ver=1784032935","caption":"Sonia"},"url":"https:\/\/focolares.es\/gl\/author\/sonia\/"}]}},"views":63,"_links":{"self":[{"href":"https:\/\/focolares.es\/gl\/wp-json\/wp\/v2\/posts\/15478","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/focolares.es\/gl\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/focolares.es\/gl\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/focolares.es\/gl\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/focolares.es\/gl\/wp-json\/wp\/v2\/comments?post=15478"}],"version-history":[{"count":4,"href":"https:\/\/focolares.es\/gl\/wp-json\/wp\/v2\/posts\/15478\/revisions"}],"predecessor-version":[{"id":15543,"href":"https:\/\/focolares.es\/gl\/wp-json\/wp\/v2\/posts\/15478\/revisions\/15543"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/focolares.es\/gl\/wp-json\/wp\/v2\/media\/15537"}],"wp:attachment":[{"href":"https:\/\/focolares.es\/gl\/wp-json\/wp\/v2\/media?parent=15478"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/focolares.es\/gl\/wp-json\/wp\/v2\/categories?post=15478"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/focolares.es\/gl\/wp-json\/wp\/v2\/tags?post=15478"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}